{"id":2285,"date":"2022-10-16T08:11:06","date_gmt":"2022-10-16T08:11:06","guid":{"rendered":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/?post_type=product&#038;p=2285"},"modified":"2025-07-26T14:15:33","modified_gmt":"2025-07-26T14:15:33","slug":"skyline-ijzendijke","status":"publish","type":"product","link":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/product\/skyline-ijzendijke\/","title":{"rendered":"Skyline IJzendijke"},"content":{"rendered":"<p>IJzendijke (Zeeuws-Vlaams: Iezendieke) is een stad in de gemeente Sluis, gelegen in het westen van Zeeuws-Vlaanderen in de Nederlandse provincie Zeeland en telt 2.475 inwoners (1 januari 2020). Tot april 1970 was IJzendijke een zelfstandige gemeente, waarna het tot 2003 deel uitmaakte van de gemeente Oostburg.<\/p>\n<p>Deze skyline van IJzendijke bevat o.a. de molen, de kerk, de muziektent en het standbeeld Prins Maurits.<\/p>\n<p><strong>Kleuren:<\/strong><\/p>\n<p>De skyline kan gespoten worden in verschillende kleuren, je kan kiezen voor blank (gewoon houtkleur van de plaat), antraciet, zwart en zilver. Wil je graag een andere kleur? Neem dan contact met ons op en vraag naar de mogelijkheden.<\/p>\n<p><strong>Maten:<\/strong><\/p>\n<p>De skylines zijn te verkrijgen in 3 breedtes: 40 cm, 60 cm en 80 cm.<\/p>\n<p>&nbsp;<\/p>\n<pre>* elk product is uniek, en kan dus wat afwijken van de getoonde afbeelding op deze site<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Leuke skyline van IJzendijke<\/p>\n","protected":false},"featured_media":2570,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_cat":[24],"product_tag":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product\/2285"}],"collection":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/comments?post=2285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/media\/2570"}],"wp:attachment":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/media?parent=2285"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_cat?post=2285"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_tag?post=2285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}