{"id":2398,"date":"2022-10-16T08:11:37","date_gmt":"2022-10-16T08:11:37","guid":{"rendered":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/?post_type=product&#038;p=2398"},"modified":"2025-07-26T13:38:23","modified_gmt":"2025-07-26T13:38:23","slug":"skyline-koudekerke","status":"publish","type":"product","link":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/product\/skyline-koudekerke\/","title":{"rendered":"Skyline Koudekerke"},"content":{"rendered":"<p>Koudekerke (Zeeuws: Koukerke) is een dorp gelegen op Walcheren in de gemeente Veere, in de Nederlandse provincie Zeeland. Het was tevens de naam van een gemeente die van 1811 tot half 1966 heeft bestaan. Met 3.360 inwoners per 1 januari 2020 is Koudekerke het grootste dorp van de gemeente. Er wonen relatief veel forensen en senioren. Het dorp heeft een traditionele band met het aan de kust gelegen Dishoek.<\/p>\n<p>De skyline van Koudekerke bevat o.a. het strand, strandpaviljoen Vloed, de kerk de molen en de &#8220;Koepel&#8221;.<\/p>\n<p><strong>Kleuren:<\/strong><\/p>\n<p>De skyline kan gespoten worden in verschillende kleuren, je kan kiezen voor blank (gewoon houtkleur van de plaat), antraciet, zwart en zilver. Wil je graag een andere kleur? Neem dan contact met ons op en vraag naar de mogelijkheden.<\/p>\n<p><strong>Maten:<\/strong><\/p>\n<p>De skylines zijn te verkrijgen in 3 breedtes: 40 cm, 60 cm en 80 cm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mooie skyline van Koudekerke<\/p>\n","protected":false},"featured_media":2578,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_cat":[24],"product_tag":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product\/2398"}],"collection":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/comments?post=2398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/media\/2578"}],"wp:attachment":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/media?parent=2398"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_cat?post=2398"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_tag?post=2398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}