{"id":3572,"date":"2025-07-27T14:09:21","date_gmt":"2025-07-27T14:09:21","guid":{"rendered":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/?post_type=product&#038;p=3572"},"modified":"2025-08-02T05:18:43","modified_gmt":"2025-08-02T05:18:43","slug":"savanne","status":"publish","type":"product","link":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/product\/savanne\/","title":{"rendered":"Savanne"},"content":{"rendered":"<p>Een sfeervolle houten wanddecoratie met een uitgesneden savanne-tafereel, waarin onder andere een giraffe, olifant en cheetah te zien zijn. Dit platte silhouet vangt de essentie van het Afrikaanse landschap<\/p>\n<p>&nbsp;<\/p>\n<pre>* elk product is uniek, en kan dus wat afwijken van de getoonde afbeelding op deze site<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Houten wanddecoratie Savanne<\/p>\n","protected":false},"featured_media":3578,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}}},"product_cat":[26],"product_tag":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product\/3572"}],"collection":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/comments?post=3572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/media\/3578"}],"wp:attachment":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/media?parent=3572"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_cat?post=3572"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_tag?post=3572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}