{"id":26,"count":14,"description":"","link":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/product-category\/dieren\/","name":"Dieren","slug":"dieren","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_cat\/26"}],"collection":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/noordhoek-graveertechniek.rnoordhoektechniek.nl\/index.php\/wp-json\/wp\/v2\/product?product_cat=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}